{"id":205335,"date":"2023-07-10T11:35:11","date_gmt":"2023-07-10T09:35:11","guid":{"rendered":"https:\/\/presse.tirol.at\/app\/uploads\/2023\/07\/Serfaus-Fiss-Ladis_Top-events-for-young-and-old-alike_summer-2023.docx"},"modified":"2023-07-10T12:02:25","modified_gmt":"2023-07-10T10:02:25","slug":"serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2","status":"inherit","type":"attachment","link":"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/","title":{"rendered":"Serfaus-Fiss-Ladis_Top events for young and old alike_summer 2023"},"author":44,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"attachment_category":[469],"attachment_tag":[],"class_list":["post-205335","attachment","type-attachment","status-inherit","hentry","attachment_category-serfaus-fiss-ladis-media-nl"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Serfaus-Fiss-Ladis_Top events for young and old alike_summer 2023 - Presse.Tirol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serfaus-Fiss-Ladis_Top events for young and old alike_summer 2023 - Presse.Tirol\" \/>\n<meta property=\"og:description\" content=\"Serfaus-Fiss-Ladis_Top events for young and old alike_summer 2023\" \/>\n<meta property=\"og:url\" content=\"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Presse.Tirol\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-10T10:02:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandra Hangl\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/\",\"url\":\"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/\",\"name\":\"Serfaus-Fiss-Ladis_Top events for young and old alike_summer 2023 - Presse.Tirol\",\"isPartOf\":{\"@id\":\"https:\/\/presse.tirol.at\/nl\/#website\"},\"datePublished\":\"2023-07-10T09:35:11+00:00\",\"dateModified\":\"2023-07-10T10:02:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Topevenementen voor groot en klein!\",\"item\":\"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Serfaus-Fiss-Ladis_Top events for young and old alike_summer 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/presse.tirol.at\/nl\/#website\",\"url\":\"https:\/\/presse.tirol.at\/nl\/\",\"name\":\"Presse.Tirol\",\"description\":\"Regionale Presseplattform der Tirol Werbung und den Tiroler Tourismusverb\u00e4nden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/presse.tirol.at\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Serfaus-Fiss-Ladis_Top events for young and old alike_summer 2023 - Presse.Tirol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/","og_locale":"nl_NL","og_type":"article","og_title":"Serfaus-Fiss-Ladis_Top events for young and old alike_summer 2023 - Presse.Tirol","og_description":"Serfaus-Fiss-Ladis_Top events for young and old alike_summer 2023","og_url":"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/","og_site_name":"Presse.Tirol","article_modified_time":"2023-07-10T10:02:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alexandra Hangl"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/","url":"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/","name":"Serfaus-Fiss-Ladis_Top events for young and old alike_summer 2023 - Presse.Tirol","isPartOf":{"@id":"https:\/\/presse.tirol.at\/nl\/#website"},"datePublished":"2023-07-10T09:35:11+00:00","dateModified":"2023-07-10T10:02:25+00:00","breadcrumb":{"@id":"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/serfaus-fiss-ladis_top-events-for-young-and-old-alike_summer-2023-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Topevenementen voor groot en klein!","item":"https:\/\/presse.tirol.at\/nl\/topevenementen-voor-groot-en-klein\/205354\/"},{"@type":"ListItem","position":2,"name":"Serfaus-Fiss-Ladis_Top events for young and old alike_summer 2023"}]},{"@type":"WebSite","@id":"https:\/\/presse.tirol.at\/nl\/#website","url":"https:\/\/presse.tirol.at\/nl\/","name":"Presse.Tirol","description":"Regionale Presseplattform der Tirol Werbung und den Tiroler Tourismusverb\u00e4nden","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/presse.tirol.at\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/presse.tirol.at\/app\/uploads\/2023\/07\/Serfaus-Fiss-Ladis_Top-events-for-young-and-old-alike_summer-2023.docx'>Serfaus-Fiss-Ladis_Top events for young and old alike_summer 2023<\/a><\/p>\n"},"caption":{"rendered":"<p>Serfaus-Fiss-Ladis_Top events for young and old alike_summer 2023<\/p>\n"},"alt_text":"","media_type":"file","mime_type":"application\/vnd.openxmlformats-officedocument.wordprocessingml.document","media_details":{"filesize":419173,"sizes":{}},"post":205354,"source_url":"https:\/\/presse.tirol.at\/app\/uploads\/2023\/07\/Serfaus-Fiss-Ladis_Top-events-for-young-and-old-alike_summer-2023.docx","_links":{"self":[{"href":"https:\/\/presse.tirol.at\/nl\/wp-json\/wp\/v2\/media\/205335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presse.tirol.at\/nl\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/presse.tirol.at\/nl\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/presse.tirol.at\/nl\/wp-json\/wp\/v2\/users\/44"}],"wp:term":[{"taxonomy":"attachment_category","embeddable":true,"href":"https:\/\/presse.tirol.at\/nl\/wp-json\/wp\/v2\/attachment_category?post=205335"},{"taxonomy":"attachment_tag","embeddable":true,"href":"https:\/\/presse.tirol.at\/nl\/wp-json\/wp\/v2\/attachment_tag?post=205335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}